{"id":1305,"date":"2015-07-18T23:34:59","date_gmt":"2015-07-16T02:19:15","guid":{"rendered":"https:\/\/youkai.gamepedia.jp\/busters\/spirits\/1305"},"modified":"2015-08-21T11:28:05","modified_gmt":"2015-08-21T02:28:05","slug":"%e7%ac%ac%e5%85%ab%e4%b8%89%e9%80%94%e4%b8%b8%e3%81%aeb%e9%ad%82","status":"publish","type":"spirit","link":"https:\/\/youkai.gamepedia.jp\/busters\/spirits\/1305","title":{"rendered":"\u3010\u30d0\u30b9\u30bf\u30fc\u30ba\u3011\u7b2c\u516b\u4e09\u9014\u4e38\u306eB\u9b42\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3011"},"content":{"rendered":"","protected":false},"author":1,"featured_media":11858,"menu_order":104,"comment_status":"open","ping_status":"open","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"2024-10-18 09:21:52","footnotes":"","kana":"","effect":"\u6b8b\u3063\u3066\u3044\u308bHP\u304c\u591a\u3044\u307b\u3069\u653b\u6483\u529b\u304c\u30a2\u30c3\u30d7\u3002"},"spirit_type":"\u30dc\u30b9\u9b42","class_list":["post-1305","spirit","type-spirit","status-publish","has-post-thumbnail","hentry","spirit_type-202"],"long_title":"\u3010\u30d0\u30b9\u30bf\u30fc\u30ba\u3011\u7b2c\u516b\u4e09\u9014\u4e38\u306eB\u9b42\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3011","user":"hiro","str_count":0,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":1,"original_content":"","site_name":"\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u30d0\u30b9\u30bf\u30fc\u30ba","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/11\/2015\/08\/01153252\/7b20c365e924a7213889739213180239.png","kana":"","effect":"\u6b8b\u3063\u3066\u3044\u308bHP\u304c\u591a\u3044\u307b\u3069\u653b\u6483\u529b\u304c\u30a2\u30c3\u30d7\u3002","_links":{"self":[{"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/spirits\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/spirits"}],"about":[{"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/types\/spirit"}],"author":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":3,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/spirits\/1305\/revisions"}],"predecessor-version":[{"id":13569,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/spirits\/1305\/revisions\/13569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/media\/11858"}],"wp:attachment":[{"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/media?parent=1305"}],"wp:term":[{"taxonomy":"spirit_type","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/busters\/wp-json\/wp\/v2\/spirit_type?post=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}