{"id":170377,"date":"2024-03-17T13:40:43","date_gmt":"2024-03-17T04:40:43","guid":{"rendered":"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/170377"},"modified":"2026-06-09T23:24:43","modified_gmt":"2026-06-09T14:24:43","slug":"%e8%b6%85%e8%a6%9a%e9%86%92%e6%bf%80%e3%83%89%e3%83%a9%e3%82%b4%e3%83%b3","status":"publish","type":"monster","link":"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/170377","title":{"rendered":"\u3010\u3077\u306b\u3077\u306b\u3011\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u5165\u624b\u65b9\u6cd5\u3068\u80fd\u529b\u8a55\u4fa1 [\u3061\u3087\u3046\u304b\u304f\u305b\u3044\u3052\u304d\u3069\u3089\u3054\u3093]\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3011"},"content":{"rendered":"<p class=\"text-s\">\n\u300c\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300d\u306b\u767b\u5834\u3059\u308b\u5996\u602a\u300c\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u300d\u306b\u95a2\u3059\u308b\u60c5\u5831\u306e\u307e\u3068\u3081\u3067\u3059\u3002\u5996\u602a\u306e\u80fd\u529b\u8a55\u4fa1\u3084\u5165\u624b\u65b9\u6cd5\u306a\u3069\u3055\u307e\u3056\u307e\u306a\u30c7\u30fc\u30bf\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002\n<\/p>\n\n<h2>\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u57fa\u672c\u60c5\u5831<\/h2>\n<div class=\"media\">\n  <div class=\"media-left\">\n    <img decoding=\"async\" class=\"media-object\" src=\"https:\/\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/03\/17031804\/IMG_9690.jpeg\" style=\"width:200px ;max-width:200px;\" \/>\n  <\/div>\n  <div class=\"clearfix visible-xs\"><\/div>\n  <div class=\"media-body\">\n    <span class=\"label label-att\">\u8f9e\u5178\u756a\u53f7<\/span> <span>8223<\/span>\n    <h4 class=\"media-heading\" style=\"margin:10px 0;\">\n      \u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3 <small>\/ \u3061\u3087\u3046\u304b\u304f\u305b\u3044\u3052\u304d\u3069\u3089\u3054\u3093<\/small>\n    <\/h4>\n    <div class=\"media-metas margin-bottom-5\">\n\n\n\n\n        <div>\n        \n\n<a class=\"btn   btn-terms btn-monster_rank btn-monster_rank-Z\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_rank=z\">Z<\/a>\n        \n\n<a class=\"btn   btn-terms btn-monster_species btn-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%83%8b%e3%83%a7%e3%83%ad%e3%83%ad%e3%83%b3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/a>\n        <\/div>\n\n        <!--\n        <div>\n        \n\n<a class=\"btn   btn-terms btn-monster_feature btn-monster_feature-\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_feature=%e3%82%b9%e3%82%bf%e3%83%bc%e3%82%bf%e3%83%bc%e3%83%91%e3%83%83%e3%82%af\">\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af<\/a>\n        <\/div>\n-->\n\n    <\/div>\n\n    <div class=\"media-desc\">\n        <div class=\"margin-bottom-5 monster-profile-row\">\n        <span class=\"label label-att\">\u597d\u7269<\/span>\n        <span class=\"monster-profile-values\">\n        \n\n        <\/span>\n        <\/div>\n\n                <div class=\"margin-bottom-5 monster-profile-row\">\n        <span class=\"label label-att\">\u5bfe\u5fdc\u30a6\u30a9\u30c3\u30c1<\/span>\n        <span class=\"monster-profile-values\">\n        \n\n<a class=\"btn   btn-terms btn-monster_watch btn-monster_watch-\u30a2\u30cb\u30de\u30b9\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_watch=%e3%82%a2%e3%83%8b%e3%83%9e%e3%82%b9\">\u30a2\u30cb\u30de\u30b9<\/a>\n<a class=\"btn   btn-terms btn-monster_watch btn-monster_watch-\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_watch=%e6%98%9f%e9%be%8d%e3%82%a6%e3%82%a9%e3%83%83%e3%83%81\">\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/a>\n<a class=\"btn   btn-terms btn-monster_watch btn-monster_watch-\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_watch=%e7%9c%9f%e3%83%bb%e6%98%9f%e9%be%8d%e3%82%a6%e3%82%a9%e3%83%83%e3%83%81\">\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/a>\n        <\/span>\n        <\/div>\n        \n                <div class=\"margin-bottom-5 monster-profile-row\">\n        <span class=\"label label-att\">\u7279\u5fb4<\/span>\n        <span class=\"monster-profile-values\">\n        \n\n<a class=\"btn   btn-terms btn-monster_feature btn-monster_feature-\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_feature=%e3%82%b9%e3%82%bf%e3%83%bc%e3%82%bf%e3%83%bc%e3%83%91%e3%83%83%e3%82%af\">\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af<\/a>\n        <\/span>\n        <\/div>\n        \n                <div class=\"margin-bottom-5 monster-profile-row\">\n        <span class=\"label label-att\" >\u5fc5\u6bba\u6280<\/span>\n        <span class=\"monster-profile-values\">\n        \n\n<a class=\"btn   btn-terms btn-special_type btn-special_type-\u3077\u306b\u6d88\u3057(\u7e26\/\u6a2a\/\u4e2d\u592e\u306a\u3069)\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?special_type=%e3%81%b7%e3%81%ab%e6%b6%88%e3%81%97%e7%b8%a6-%e6%a8%aa-%e4%b8%ad%e5%a4%ae%e3%81%aa%e3%81%a9\">\u3077\u306b\u6d88\u3057(\u7e26\/\u6a2a\/\u4e2d\u592e\u306a\u3069)<\/a>\n        <\/span>\n        <\/div>\n        \n                <div class=\"margin-bottom-5 monster-profile-row\">\n        <span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span>\n        <span class=\"monster-profile-values\">\n        \n\n<a class=\"btn   btn-terms btn-monster_skill_type btn-monster_skill_type-\u30dc\u30fc\u30ca\u30b9\u7389\u304c\u964d\u3063\u3066\u304f\u308b\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_skill_type=%e3%83%9c%e3%83%bc%e3%83%8a%e3%82%b9%e7%8e%89%e3%81%8c%e9%99%8d%e3%81%a3%e3%81%a6%e3%81%8f%e3%82%8b\">\u30dc\u30fc\u30ca\u30b9\u7389\u304c\u964d\u3063\u3066\u304f\u308b<\/a>\n        <\/span>\n        <\/div>\n        \n\n<!--\n        <div>\n                <a class=\"underline\" href=\"https:\/\/youkai-pedia.com\/monsters\/\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\"><i class=\"fa fa-external-link\"><\/i> \u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306f\u3069\u3093\u306a\u5996\u602a\uff1f<\/a>\n                <\/div>\n-->\n    <\/div>\n  <\/div>\n  <div class=\"clearfix\"><\/div>\n<\/div>\n\n\n\n<div>\n<h2><span id=\"i-2\"><span id=\"i-3\"><span id=\"OSVer3-3\"><span id=\"KB92-2\"><span id=\"i\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u7dcf\u5408\u8a55\u4fa1<\/span><\/span><\/span><\/span><\/span><\/h2>\n<h3><span id=\"2\"><span id=\"i\"><span id=\"i-3\"><span id=\"i-4\">\u30cb\u30e7\u30ed\u30ed\u30f3\u306e\u30a2\u30bf\u30c3\u30ab\u30fc<\/span><\/span><\/span><\/span><\/h3>\n<p><span class=\"text-s\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306f\u300c\u534a\u5996\u306e\u6ec5\u9f8d\u58eb2<span>\u301c\u9f8d\u4ed9\u90f7\u7de8\u301c<\/span>\u300d\u3067\u767b\u5834\u3057\u305f<\/span><span class=\"text-s\">Z\u30e9\u30f3\u30af\u306e\u30cb\u30e7\u30ed\u30ed\u30f3\u65cf\u30ad\u30e3\u30e9\u3067\u3059\u3002<\/span><\/p>\n<p><span class=\"text-s\">Z<span>\u30e9\u30f3\u30af\u306f\u30ec\u30d9\u30eb60\u307e\u3067\u80b2\u6210\u53ef\u80fd\u3067\u3001\u300cLv50\u2192Lv60\u300d\u306e\u30ec\u30d9\u30eb\u4e0a\u9650\u958b\u653e\u6642\u306bY\u30dd\u30a4\u30f3\u30c8\u304c1500pt\u5fc5\u8981\u3067\u3059\u3002<\/span><\/span><\/p>\n<p><span class=\"text-s\">\u5fc5\u6bba\u6280\u3092\u767a\u52d5\u3059\u308b\u3068\u76e4\u9762\u306b\u3042\u308b\u5996\u602a\u3077\u306b\u3092\u5168\u3066\u6d88\u3057\u3001\u6575\u306b\u30c0\u30e1\u30fc\u30b8\u3092\u4e0e\u3048\u307e\u3059\u3002<\/span><\/p>\n<p><span class=\"text-s\"><span>\u81ea\u8eab\u306e\u5996\u602a\u3077\u306b\u306e\u4ee3\u308f\u308a\u306b\u30dc\u30fc\u30ca\u30b9\u7389\u304c\u964d\u3063\u3066\u304f\u308b\u30b9\u30ad\u30eb\u3092\u6301\u3063\u3066\u3044\u308b\u306e\u3067\u3001\u30dc\u30fc\u30ca\u30b9\u7389\u306e\u30df\u30c3\u30b7\u30e7\u30f3\u3092\u30af\u30ea\u30a2\u3057\u305f\u3044\u3068\u304d\u306b\u7de8\u6210\u306b\u52a0\u3048\u3066\u307f\u307e\u3057\u3087\u3046\u3002<\/span><\/span><\/p>\n<p><span class=\"text-s\">\u30a4\u30d9\u30f3\u30c8\u671f\u9593\u4e2d(3\/17\u301c3\/31)\u306f\u3001\u30c8\u30fc\u30ca\u30e1\u30f3\u30c8\u306e\u5168\u3066\u306e\u6575\u3084\u6311\u6226\u8005\u306e\u8d85\u899a\u9192\u9752\u9f8d\u306b\u5bfe\u3057\u3066\u3068\u3001<span>\u300c\u3088\u3053\u3069\u308a\u6642\u306b\u305f\u307e\u306b\u3064\u3088\u3055\u304c\u8d85\u30a2\u30c3\u30d7\u300d\u306e\u7279\u6b8a\u80fd\u529b\u3092\u767a\u63ee\u3057\u307e\u3059\u3002<\/span><\/span><\/p>\n<h3><span id=\"i-4\"><span id=\"i-2\"><span id=\"i-5\"><span id=\"i-3\">\u8ab2\u91d1\u30ad\u30e3\u30e9<\/span><\/span><\/span><\/span><\/h3>\n<p><span class=\"text-s\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u5165\u624b\u65b9\u6cd5\u306f\u300c\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\u300d\u3067\u8cfc\u5165\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/span><\/p>\n<p><span class=\"text-s\"><span>\u8ab2\u91d1\u3059\u308c\u3070\u78ba\u5b9f\u306b\u5165\u624b\u3067\u304d\u308b\u30ad\u30e3\u30e9\u3067\u3059\u304c\u3001\u30a4\u30d9\u30f3\u30c8\u7d42\u4e86\u5f8c\u306e\u6d3b\u8e8d\u306f\u898b\u8fbc\u3081\u307e\u305b\u3093\u3002<\/span><\/span><\/p>\n<p><span class=\"text-s\"><span>\u3069\u3046\u3057\u3066\u3082\u3053\u306e\u7279\u653b\u30ad\u30e3\u30e9\u304c\u5fc5\u8981\u306a\u5834\u5408\u306f\u8cfc\u5165\u3057\u3066\u307f\u307e\u3057\u3087\u3046\u3002<\/span><\/span><\/p>\n<\/div>\n\n<h2 >\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u80fd\u529b<\/h2>\n<h3 class=\"\">\u30b9\u30c6\u30fc\u30bf\u30b9<\/h3>\n<div class=\"\">\n<table style=\"max-width:320px;\">\n  <tr><th><\/th><th>HP<\/th><th>\u3053\u3046\u3052\u304d<\/th><\/tr>\n    <tr>\n   <td>Lv1<\/td>\n   <td>509<\/td>\n   <td>586<\/td>\n  <\/tr>\n  \n  \t\n      \t\t\t\t\t\t\t      <tr>\n\t\t\t\t\t\t\t       <td>Lv60<\/td>\n\t\t\t\t\t\t\t       <td>899\t\t\t\t\t\t\t       <\/td>\n\t\t\t\t\t\t\t       <td>1034\t\t\t\t\t\t\t       <\/td>\n\t\t\t\t\t\t\t      <\/tr>\n\t\t\t\t\t\t\t      <tr>\n\t\t\t\t\t\t\t      <td>Lv60\u203b<\/td>\n\t\t\t\t\t\t\t       <td>899\t\t\t\t\t\t\t       <\/td>\n\t\t\t\t\t\t\t       <td>1551\t\t\t\t\t\t\t       <\/td>\n\t\t\t\t\t\t\t      <\/tr>\n\t\t\t\t\t\t\t      \n  <\/table>\n\n<span class=\"text-s\">\u203b\n<span class=\"empty-link\">\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/span> \u88c5\u7740\u6642<\/span>\n<\/div>\n\n<h3>\u30b9\u30ad\u30eb<\/h3>\n\n<strong>\u30b9\u30ad\u30eb1<\/strong>\n<div class=\"note-white\">\u81ea\u8eab\u306e\u5996\u602a\u3077\u306b\u306e\u4ee3\u308f\u308a\u306b\u30dc\u30fc\u30ca\u30b9\u7389\u304c\u3075\u3063\u3066\u304f\u308b:7%<\/div>\n\n\n\n\n\n\n<h3>G\u6280<\/h3>\n<div class=\"note-white\">\u5f37\u529b\u306a \u30c9\u30e9\u30b4\u30f3\u6fc0\u4e00\u767a\u3092\u306f\u306a\u3064<\/div>\n\n\n<h3>\u5fc5\u6bba\u6280<\/h3>\n<div class=\"note-white margin-bottom-5\">\n  <span class=\"label label-primary\">\u3077\u306b\u5168\u6d88\u3057<\/span><br>\n  <span class=\"weak\">\u30c9\u30e9\u30b4\u30f3\u6fc0\u4e00\u767a<\/span><br>\n  <div>\u5168\u3066\u306e\u5996\u602a\u3077\u306b\u3092\u6d88\u3057 1\u4f53\u653b\u6483<\/div>\n\n<\/div>\n\n<div class=\"\">\n<h4>\u308f\u3056\u52b9\u679c<\/h4>\n<table>\n    <tr>\n  <td>\n    <span class=\"\">Lv1<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">92pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv2<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">101pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv3<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">110pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv4<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">119pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv5<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">128pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv6<\/span>\n  <\/td>\n  <td>\n                                <span class=\"label-att\">\u3044\u308a\u3087\u304f<\/span><span class=\"label label-value\">137pt<\/span><br>\n              <\/td>\n  <\/tr>\n    <tr>\n  <td>\n    <span class=\"\">Lv7<\/span>\n  <\/td>\n  <td>\n                          <\/td>\n  <\/tr>\n  <\/table>\n<\/div>\n<div class=\"weak\">\n\u203b\u4e00\u90e8\u5996\u602a\u306e\u5fc5\u6bba\u6280\u52b9\u679c\u306f\u63a8\u6e2c\u3057\u305f\u3082\u306e\u3092\u63b2\u8f09\u3057\u3066\u3044\u307e\u3059\u3002<br>\n\u203b\u307f\u306a\u3055\u307e\u304b\u3089\u306e<a href=\"#respond\">\u60c5\u5831\u63d0\u4f9b<\/a>\u3082\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\u3002\n<\/div>\n\n\n<h3>\u76f8\u6027<\/h3>\n<div class=\"\">\n<div>\n<span class=\"label label-att\">\u5f97\u610f\u306a\u7a2e\u65cf<\/span>\n\n\n<a class=\"btn   btn-terms btn-monster_species btn-monster_species-\u30d7\u30ea\u30c1\u30fc\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%83%97%e3%83%aa%e3%83%81%e3%83%bc\">\u30d7\u30ea\u30c1\u30fc<\/a>\n\n\n<a class=\"btn   btn-terms btn-monster_species btn-monster_species-\u30dd\u30ab\u30dd\u30ab\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%83%9d%e3%82%ab%e3%83%9d%e3%82%ab\">\u30dd\u30ab\u30dd\u30ab<\/a>\n<\/div>\n\n<div>\n<span class=\"label label-att\">\u82e6\u624b\u306a\u7a2e\u65cf<\/span>\n\n\n<a class=\"btn   btn-terms btn-monster_species btn-monster_species-\u30a4\u30b5\u30de\u30b7\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%82%a4%e3%82%b5%e3%83%9e%e3%82%b7\">\u30a4\u30b5\u30de\u30b7<\/a>\n\n\n<a class=\"btn   btn-terms btn-monster_species btn-monster_species-\u30b4\u30fc\u30b1\u30c4\" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%82%b4%e3%83%bc%e3%82%b1%e3%83%84\">\u30b4\u30fc\u30b1\u30c4<\/a>\n<\/div>\n<\/div>\n<a href=\"\/punipuni\/archives\/5775\"><i class=\"fa fa-arrow-circle-right\"><\/i> \u76f8\u6027\u52b9\u679c\u306b\u3064\u3044\u3066<\/a>\n\n\n\n<h2  class=\"headline\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u5165\u624b\u65b9\u6cd5<\/h2>\n\n\n<h3  class=\"\">\u5996\u602a\u30ac\u30b7\u30e3\u304b\u3089\u51fa\u73fe<\/h3>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/gashas\/184045\">\n  <div class=\"media media-gasha\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/12\/17142847\/B5D11312-279E-4A4D-B509-FAF4865B2CC9.jpeg\" width=\"80\" height=\"80\" style=\"max-width:100px;\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30ea\u30bc\u30ed\u30b3\u30a4\u30f3      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2024\u5e7412\u670817\u65e5        <\/small>\n        \n        \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30ea\u30bc\u30ed\u30b3\u30a4\u30f3\u30ac\u30b7\u30e3\u3067\u51fa\u73fe\u3059\u308b\u5996\u602a\u4e00\u89a7      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/gashas\/190601\">\n  <div class=\"media media-gasha\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/05\/03054655\/IMG_6241.jpeg\" width=\"80\" height=\"80\" style=\"max-width:100px;\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u306b\u3058\u3055\u3093\u3058\u30b3\u30a4\u30f3      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2025\u5e745\u67083\u65e5        <\/small>\n        \n        \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u306b\u3058\u3055\u3093\u3058\u30b3\u30a4\u30f3\u30ac\u30b7\u30e3\u3067\u51fa\u73fe\u3059\u308b\u5996\u602a\u4e00\u89a7      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/gashas\/194606\">\n  <div class=\"media media-gasha\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/08\/03154134\/IMG_9877.jpeg\" width=\"80\" height=\"80\" style=\"max-width:100px;\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2025\u5e748\u67083\u65e5        <\/small>\n        \n        \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3\u30ac\u30b7\u30e3\u3067\u51fa\u73fe\u3059\u308b\u5996\u602a\u4e00\u89a7      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-image-list-image-list-1265353138\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-image-list-image-list-1265353138\" class=\"collapse\">\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/gashas\/15869\">\n  <div class=\"media media-gasha\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai-punipuni\/wp-content\/uploads\/2016\/07\/23131256\/image-96.jpeg\" width=\"80\" height=\"80\" style=\"max-width:100px;\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u6c34\u8272\u30b3\u30a4\u30f3G      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2016\u5e744\u670829\u65e5        <\/small>\n        \n        \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u6c34\u8272\u30b3\u30a4\u30f3G\u30ac\u30b7\u30e3\u3067\u51fa\u73fe\u3059\u308b\u5996\u602a\u4e00\u89a7      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n\n<h3  class=\"\">\u305d\u306e\u4ed6\u306e\u5165\u624b\u65b9\u6cd5<\/h3>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/170389\">\n  <div class=\"media media-other-drop\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/03\/17142430\/IMG_9699-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u6ec5\u9f8d\u58eb2(\u9f8d\u4ed9\u90f7\u7de8)\uff1a\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2024\u5e743\u670819\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u305d\u306e\u4ed6\u30c9\u30ed\u30c3\u30d7\">\u305d\u306e\u4ed6\u30c9\u30ed\u30c3\u30d7<\/span>\n                \n\n\n        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u6700\u65b0\u30a4\u30d9\u30f3\u30c8\u306e\u65b0\u30ad\u30e3\u30e9\/\u3088\u3070\u308c\u65b9\u5165\u624b\u65b9\u6cd5\u307e\u3068\u3081(3\/24\u8ffd\u8a18)\uff5c\u6ec5\u9f8d\u58eb2(\u9f8d\u4ed9\u90f7\u7de8)      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n\n\n\n\n\n<h2 class=\"headline\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u95a2\u9023\u8a18\u4e8b<\/h2>\n<ul class=\"media-list image-list \">\n  <div>\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/142852\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/08\/01130303\/7CE6D7E0-F9B7-419E-8183-FD1A2721A447-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u4e94\u6708(\u590f\u670d)\u306e\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\/\u30d3\u30ae\u30ca\u30fc\u30d1\u30c3\u30af\u8ca9\u58f2\u4e2d\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2026\u5e749\u67082\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\">\u30ad\u30e3\u30f3\u30da\u30fc\u30f3<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\">\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u3067\u8cfc\u5165\u3067\u304d\u308b\u300c\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\u300d\u300c\u30d3\u30ae\u30ca\u30fc\u30d1\u30c3\u30af\u300d\u3092\u7d39...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/212824\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/17044529\/IMG_2524-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u304b\u306e\u304b\u308a\u30df\u30cb\u30b3\u30e9\u30dc\u30d3\u30f3\u30b4\u306e\u904a\u3073\u65b9\uff01\u30c7\u30fc\u30c8\u30c1\u30b1\u30c3\u30c8\u3067\u56de\u3059\u30df\u30cb\u30b3\u30e9\u30dc\u30ac\u30b7\u30e3\u306e\u4e2d\u8eab\u3092\u7d39\u4ecb\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2026\u5e748\u670817\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30a4\u30d9\u30f3\u30c8\">\u30a4\u30d9\u30f3\u30c8<\/span>\n                <span class=\"label label-default label-category label-category-\u30df\u30cb\u30b3\u30e9\u30dc\">\u30df\u30cb\u30b3\u30e9\u30dc<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u304b\u306e\u304b\u308a\">\u304b\u306e\u304b\u308a<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u3067\u767b\u5834\u3059\u308b\u300c\u30df\u30cb\u30b3\u30e9\u30dc\u30d3\u30f3\u30b4\u300d\u306e\u904a\u3073\u65b9\u3084\u3001\u30c7\u30fc\u30c8\u30c1\u30b1...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/210292\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/11\/15200506\/IMG_4592-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30d7\u30ec\u30df\u30a2\u30e0\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\u767b\u5834\uff01\u4e2d\u8eab\u3068\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2026\u5e748\u67081\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\">\u30ac\u30b7\u30e3<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\">\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u300e\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300f\u306b\u767b\u5834\u3057\u305f\u300c\u30d7\u30ec\u30df\u30a2\u30e0\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\u300d\u306e\u56de\u3057...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n    <\/div>\n    <div class=\"nav-more\" style=\"margin-top:10px;\">\n        <a class=\"btn btn-nav-more hide-me\" data-toggle=\"collapse\" href=\"#collapse-image-list-image-list-1987135993\">\u3082\u3063\u3068\u898b\u308b<\/a>\n    <\/div>\n    <div id=\"collapse-image-list-image-list-1987135993\" class=\"collapse\">\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/169997\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/07\/19194055\/IMG_9082-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u8d85\u7dd1\u30b3\u30a4\u30f3 \u518d\u30ea\u30cb\u30e5\u30fc\u30a2\u30eb\u8ca9\u58f2\uff01\u795e\u7dd1\u82b1\u3055\u304b\u723a\u767b\u5834\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2026\u5e746\u670817\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\">\u30ad\u30e3\u30f3\u30da\u30fc\u30f3<\/span>\n                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3\">\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u3067\u306f\u7279\u5225\u306a\u30b3\u30a4\u30f3\u304c\u8ca9\u58f2\u4e2d\u3067\u3059\u3002\r\n\u8ca9\u58f2\u671f\u9593\r\n\r\n2026\u5e74\r\n6...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/199687\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/11\/15200506\/IMG_4592-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\u767b\u5834\uff01\u4e2d\u8eab\u3068\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2026\u5e743\u67081\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\">\u30ac\u30b7\u30e3<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\">\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u300e\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300f\u306b\u767b\u5834\u3057\u305f\u300c\u307e\u308f\u3057\u653e\u984cVIP\u30ac\u30b7\u30e3\u300d\u306e\u56de\u3057\u65b9\u3084\u30ac\u30b7\u30e3...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/194597\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/08\/03154134\/IMG_9877.jpeg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068\u4e2d\u8eab\u306f\u3053\u3061\u3089\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2025\u5e748\u67083\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3\">\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3\">\u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300f\u3067\u4f7f\u3048\u308b\u300c\u7121\u8077\u8ee2\u751f\u30b3\u30a4\u30f3\u300d\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068\u4e2d...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/192640\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/06\/17155149\/BE76867E-11C6-4057-8A8A-3742E8C6B2F0-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u5fa9\u523b\u30ae\u30f3\u30ac\u30a6\u30a9\u30c3\u30c1\u30ac\u30b7\u30e3\u767b\u5834\uff01\u30ac\u30b7\u30e3\u30b9\u30bf\u30f3\u30d7\u4ed8\u304d\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2025\u5e746\u670817\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\">\u30ac\u30b7\u30e3<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ae\u30f3\u30ac\u30a6\u30a9\u30c3\u30c1\u30ac\u30b7\u30e3\">\u30ae\u30f3\u30ac\u30a6\u30a9\u30c3\u30c1\u30ac\u30b7\u30e3<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\nY\u30dd\u30a4\u30f3\u30c8\u3067\u56de\u305b\u308b\u5fa9\u523b\u30ae\u30f3\u30ac\u30a6\u30a9\u30c3\u30c1\u30ac\u30b7\u30e3\u304c\u767b\u5834\u3057\u307e\u3057\u305f\u3002\r\n\r\n\u3053\u306e\u30ac\u30b7\u30e3\u306b...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/190592\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2025\/05\/03054655\/IMG_6241.jpeg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u306b\u3058\u3055\u3093\u3058\u30b3\u30a4\u30f3\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068\u4e2d\u8eab\u306f\u3053\u3061\u3089\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2025\u5e745\u67083\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3\">\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300f\u3067\u4f7f\u3048\u308b\u300c\u306b\u3058\u3055\u3093\u3058\u30b3\u30a4\u30f3\u300d\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/184093\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/12\/17142847\/B5D11312-279E-4A4D-B509-FAF4865B2CC9.jpeg\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30ea\u30bc\u30ed\u30b3\u30a4\u30f3\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068\u4e2d\u8eab\u306f\u3053\u3061\u3089\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2024\u5e7412\u670817\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3\">\u30ac\u30b7\u30e3\u30b3\u30a4\u30f3<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u300e\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300f\u3067\u4f7f\u3048\u308b\u300c\u30ec\u30ea\u30bc\u30ed\u30b3\u30a4\u30f3\u300d\u306e\u304a\u3059\u3059\u3081\u5f53\u305f\u308a\u30ad\u30e3\u30e9\u3068\u4e2d...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/170621\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2023\/02\/27070317\/B31795FA-577F-4E57-A391-95E993E0EE03-480x252.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u6709\u6599\u30a2\u30a4\u30c6\u30e0\u8cfc\u5165\u6642\u306b\u30a8\u30e9\u30fc(3\/29\u88dc\u586b\u914d\u5e03)\/\u3088\u3053\u3069\u308a\u30d0\u30c8\u30eb\u306e\u4e0d\u5177\u5408(\u88dc\u586b\u914d\u5e03)\uff5c\u4e0d\u5177\u5408      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2024\u5e743\u670829\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u4e0d\u5177\u5408\">\u4e0d\u5177\u5408<\/span>\n                                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \r\n\r\n\u300c\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b\u300d\u3067\u767a\u751f\u3057\u3066\u3044\u308b\u4e0d\u5177\u5408\u3084\u30d0\u30b0\u306e\u60c5\u5831\u3092\u307e\u3068\u3081\u307e\u3057\u305f\u3002\r...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n<a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/archives\/14461\">\n  <div class=\"media media-post\">\n    <div class=\"media-left\">\n      <img decoding=\"async\" class=\"media-object\" loading=\"lazy\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=150,h=150,fit=pad,f=webp\/media.gamepedia.jp\/youkai-punipuni\/wp-content\/uploads\/2016\/04\/23132801\/yamatan.png\" width=\"80\" height=\"80\" style=\"\"  \/>\n            <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n        \n        \u30ec\u30b8\u30a7\u30f3\u30c9\u5996\u602a \u3084\u307e\u30bf\u30f3 \u89e3\u653e\u5996\u602a\u306e\u96c6\u3081\u65b9\uff01      <\/div>\n      <div class=\"media-meta\">\n\n        \n                <small class=\"media-meta-date\">\n          2016\u5e744\u670822\u65e5        <\/small>\n        \n                        <span class=\"label label-default label-post-type label-post-type-\u6295\u7a3f\">\u6295\u7a3f<\/span>\n                \n\n\n                                <span class=\"label label-default label-category label-category-\u304a\u5f79\u7acb\u3061\">\u304a\u5f79\u7acb\u3061<\/span>\n                                <span class=\"label label-default label-post_tag label-post_tag-\u30ec\u30b8\u30a7\u30f3\u30c9\">\u30ec\u30b8\u30a7\u30f3\u30c9<\/span>\n                <span class=\"label label-default label-post_tag label-post_tag-\u5996\u602a\">\u5996\u602a<\/span>\n                                        \n\n      <\/div>\n            <div class=\"media-desc\">\n        \u30ec\u30b8\u30a7\u30f3\u30c9\u5996\u602a\u3084\u307e\u30bf\u30f3\u306e\u5c01\u5370\u5996\u602a6\u4f53\u306e\u96c6\u3081\u65b9\u3092\u7d39\u4ecb\u3057\u307e\u3059\u3002\r\n\r\n\r\n\u516b\u767e\u6bd4\u4e18\u5c3c\r\n\r\n...      <\/div>\n      \n    <\/div>\n    <div class=\"clearfix\"><\/div>\n  <\/div>\n<\/a>\n\n  <\/div>\n<\/ul>\n\n\n<h2  class=\"headline\">\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u52d5\u753b<\/h2>\n\n\n\n<h2  class=\"headline\">\u95a2\u9023\u5996\u602a<\/h2>\n\n\n<h3  class=\"\">\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\u306e\u5996\u602a<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212994\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/17203240\/IMG_2592.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30ad\u30e9\u30a4\u30ae\u30e7              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1185<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1995<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u4e2d\u592e\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b\u3001\u3068\u308a\u3064\u304d(\u3086\u3060\u3093)\u3092\u77ed\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212357\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/01002709\/IMG_1484.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30d7\u30ea\u30c1\u30fc\">\u30d7\u30ea\u30c1\u30fc<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u899a\u9192\u30e6\u30a4              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1220<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1943<\/span> <small> \u203b\u3077\u306b\u795e\u30a6\u30a9\u30c3\u30c1\u30fb\u84ee<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u653b\u6483\u529b\u30a2\u30c3\u30d7+\u3067\u304b\u3077\u306b\u751f\u6210<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3067\u304b\u3077\u306b\u6d88\u3059\u3068\u4ed6\u5996\u602a\u6280\u30b2\u30fc\u30b8UP\u3001\u5fa9\u6d3b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/211850\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/07\/17002625\/IMG_1364-1.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30d5\u30af\u30ea\u30e5\u30a6              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1168<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >2021<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u30c0\u30e1\u30fc\u30b8\u6e1b\u5c11\u3001\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/211206\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/07\/01003204\/IMG_1259.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30a4\u30b5\u30de\u30b7\">\u30a4\u30b5\u30de\u30b7<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30cb\u30e3\u30f3\u9a0e\u58eb              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1454<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1690<\/span> <small> \u203b\u8ee2\u751f\u52c7\u8005\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u30c0\u30e1\u30fc\u30b8\u6e1b\u5c11\u3001\u81ea\u8eab\u306e\u6280\u4f7f\u7528\u5f8c\u306bHP\u56de\u5fa9<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/210661\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/06\/16002302\/IMG_1126.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u6885\u96e8\u30ad\u30e5\u30a6\u30d3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1030<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1757<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u5206\u4ee5\u5916\u304c\u6280\u3092\u4f7f\u3046\u3068\u6280\u30b2\u30fc\u30b8UP\u3001\u81ea\u8eab\u306e\u5996\u602a\u3077\u306b\u3092\u51fa\u3084\u3059\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/209302\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/05\/17125538\/IMG_0840.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30d6\u30ad\u30df\u30fc\">\u30d6\u30ad\u30df\u30fc<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u72c2\u721b\u306e\u82b1\u5b50\u3055\u3093              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1343<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1402<\/span> <small> \u203b\u30a2\u30a4\u30ed\u30ef\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u6280\u4f7f\u7528\u5f8c\u306b\u6280\u30b2\u30fc\u30b8\u304c\u6b8b\u308b\u3001\u81ea\u5206\u4ee5\u5916\u304c\u6280\u3092\u4f7f\u3046\u3068\u6280\u30b2\u30fc\u30b8UP<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_feature=%e3%82%b9%e3%82%bf%e3%83%bc%e3%82%bf%e3%83%bc%e3%83%91%e3%83%83%e3%82%af&sort=newest\" target=\"\" >\n    \u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af\u306e\u5996\u602a\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n<h3  class=\"\">\u3077\u306b\u6d88\u3057(\u7e26\/\u6a2a\/\u4e2d\u592e\u306a\u3069)\u306e\u304a\u3059\u3059\u3081\u5996\u602a<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/213493\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/09\/01003814\/IMG_1734.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30dd\u30ab\u30dd\u30ab\">\u30dd\u30ab\u30dd\u30ab<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u56db\u8449(\u590f\u670d)              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1491<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1642<\/span> <small> \u203b\u30a2\u30a4\u30ed\u30ef\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u4e2d\u592e\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u8eab\u306e\u6280\u4f7f\u7528\u5f8c\u306bHP\u56de\u5fa9\u3001\u5fa9\u6d3b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/213492\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/09\/01003822\/IMG_1733.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30a6\u30b9\u30e9\u30ab\u30b2\">\u30a6\u30b9\u30e9\u30ab\u30b2<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u4e09\u7396(\u590f\u670d)              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1491<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1642<\/span> <small> \u203b\u30a2\u30a4\u30ed\u30ef\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u6a2a\u65b9\u5411\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3055\u307c\u3089\u305b\u308b\u3001\u5fa9\u6d3b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/213491\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/09\/01003830\/IMG_1732.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30d6\u30ad\u30df\u30fc\">\u30d6\u30ad\u30df\u30fc<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u4e8c\u4e43(\u590f\u670d)              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1491<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1642<\/span> <small> \u203b\u30a2\u30a4\u30ed\u30ef\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u7e26\u306b\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b\u3001\u5fa9\u6d3b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212994\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/17203240\/IMG_2592.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30ad\u30e9\u30a4\u30ae\u30e7              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1185<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1995<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u4e2d\u592e\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b\u3001\u3068\u308a\u3064\u304d(\u3086\u3060\u3093)\u3092\u77ed\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212361\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/01002612\/IMG_1492.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30a4\u30b5\u30de\u30b7\">\u30a4\u30b5\u30de\u30b7<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30e6\u30fc\u30b8\u30aa(UW)              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >830<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1251<\/span> <small> \u203b\u8ee2\u751f\u52c7\u8005\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u4e2d\u592e\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" >\u3044\u308a\u3087\u304f:84pt<\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u8eab\u306e\u3077\u306b\u304c\u3064\u306a\u304c\u308a\u3084\u3059\u3044<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212359\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/01002627\/IMG_1490.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30dd\u30ab\u30dd\u30ab\">\u30dd\u30ab\u30dd\u30ab<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30b7\u30ea\u30ab(SAO)              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >870<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1195<\/span> <small> \u203b\u30a2\u30a4\u30ed\u30ef\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u6a2a\u65b9\u5411\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" >\u3044\u308a\u3087\u304f:86pt<\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u8eab\u304c\u3067\u304b\u3077\u306b\u3067\u964d\u3063\u3066\u304f\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?special_type=%e3%81%b7%e3%81%ab%e6%b6%88%e3%81%97%e7%b8%a6-%e6%a8%aa-%e4%b8%ad%e5%a4%ae%e3%81%aa%e3%81%a9\" target=\"\" >\n    \u3077\u306b\u6d88\u3057(\u7e26\/\u6a2a\/\u4e2d\u592e\u306a\u3069)\u306e\u304a\u3059\u3059\u3081\u5996\u602a\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n<h3  class=\"\">\u30cb\u30e7\u30ed\u30ed\u30f3\u65cf\u306e\u304a\u3059\u3059\u3081\u5996\u602a<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212994\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/17203240\/IMG_2592.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30ad\u30e9\u30a4\u30ae\u30e7              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1185<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1995<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u4e2d\u592e\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b\u3001\u3068\u308a\u3064\u304d(\u3086\u3060\u3093)\u3092\u77ed\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/212990\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/08\/17203310\/IMG_2588.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u590f\u82b1\u76db\u308a\u4f0f\u674e\u30e6\u30a6              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1479<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >2132<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057+\u3077\u306b\u6574\u7406<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u8eab\u304c\u3067\u304b\u3077\u306b\u3067\u964d\u3063\u3066\u304f\u308b\u3001\u5fa9\u6d3b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/211850\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/07\/17002625\/IMG_1364-1.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u30d5\u30af\u30ea\u30e5\u30a6              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1168<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >2021<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u30c0\u30e1\u30fc\u30b8\u6e1b\u5c11\u3001\u3068\u308a\u3064\u304d(\u3069\u304f)\u3092\u77ed\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/211201\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/07\/01003238\/IMG_1254.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u6226\u58eb\u30aa\u30ed\u30c1              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1562<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >2652<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u5927\u91cf\u3077\u306b\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u8eab\u3092\u7e4b\u3052\u3066\u30d5\u30a3\u30fc\u30d0\u30fc\u30b2\u30fc\u30b8UP\u3001\u81ea\u8eab\u304c\u3067\u304b\u3077\u306b\u3067\u964d\u3063\u3066\u304f\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/210661\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/06\/16002302\/IMG_1126.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u8d85\u899a\u9192\u6885\u96e8\u30ad\u30e5\u30a6\u30d3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1030<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >1757<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u81ea\u5206\u4ee5\u5916\u304c\u6280\u3092\u4f7f\u3046\u3068\u6280\u30b2\u30fc\u30b8UP\u3001\u81ea\u8eab\u306e\u5996\u602a\u3077\u306b\u3092\u51fa\u3084\u3059\u304f\u3059\u308b<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters\/209294\">\n    <div class=\"media media-monster media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2026\/05\/17125610\/IMG_0835.jpeg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u5996\u602a\">\u5996\u602a<\/span>\n                \n                                        <span class=\"label label-default label-monster_species label-monster_species-\u30cb\u30e7\u30ed\u30ed\u30f3\">\u30cb\u30e7\u30ed\u30ed\u30f3<\/span>\n                                                                                                                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u84bc\u5d50\u3084\u307e\u30bf\u30f3              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"margin-bottom-5\"> <span class=\"label label-att\">HP<\/span><span class=\"label label-value\" >1906<\/span> <span class=\"label label-att\">\u653b\u6483<\/span><span class=\"label label-value\" >2511<\/span> <small> \u203b\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1<\/small><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5fc5\u6bba\u6280<\/span><br><span class=\"label label-value \" style=\"word-break:break-all; white-space:normal;\">\u3077\u306b\u5168\u6d88\u3057+\u30d5\u30a3\u30fc\u30d0\u30fc\u5f37\u5316<\/span><br class=\"visible-xs\"> <span class=\"text-s\" ><\/span><\/div><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u30b9\u30ad\u30eb<\/span><br><span class=\"label label-value text-s\" style=\"word-break:break-all; white-space:normal;text-align:left;\">\u7a2e\u65cf\u52b9\u679c\u30a2\u30c3\u30d7\u3001\u30d5\u30a3\u30fc\u30d0\u30fc\u4e2d\u306b\u30d1\u30ef\u30fc\u30a2\u30c3\u30d7<\/span><\/div><hr class=\"no-margin margin-bottom-5\" \/><div class=\"margin-bottom-5\"><span class=\"label label-att\">\u5165\u624b\u65b9\u6cd5<\/span><br> <span class=\"text-s text-black\"><\/span><\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n        <\/div>\n<\/ul>\n<hr class=\"spacer-5\" >\n<div class=\"nav-more\">\n<a class=\"btn btn-nav-more \" href=\"https:\/\/youkai.gamepedia.jp\/punipuni\/monsters?monster_species=%e3%83%8b%e3%83%a7%e3%83%ad%e3%83%ad%e3%83%b3\" target=\"\" >\n    \u30cb\u30e7\u30ed\u30ed\u30f3\u65cf\u306e\u304a\u3059\u3059\u3081\u5996\u602a\u3092\u3082\u3063\u3068\u898b\u308b<\/a>\n<\/div>\n\n\n\n","protected":false},"author":6,"featured_media":170360,"menu_order":8223,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"","footnotes":"","kana":"\u3061\u3087\u3046\u304b\u304f\u305b\u3044\u3052\u304d\u3069\u3089\u3054\u3093","name":"\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3","number":"8223","score":"","score_rank":"","rank_order":"9","special_name":"\u30c9\u30e9\u30b4\u30f3\u6fc0\u4e00\u767a","special_type":"\u3077\u306b\u5168\u6d88\u3057","special_description":"\u5168\u3066\u306e\u5996\u602a\u3077\u306b\u3092\u6d88\u3057 1\u4f53\u653b\u6483","special_min_effect":"","special_max_effect":"","special_max_level":"","max_attack":"1034","max_hp":"899","min_attack":"586","min_hp":"509","all":"2450","source":""},"monster_species":"\u30cb\u30e7\u30ed\u30ed\u30f3","monster_rank":"Z","special_type":"\u3077\u306b\u5168\u6d88\u3057","monster_favorite":"","monster_feature":"\u30b9\u30bf\u30fc\u30bf\u30fc\u30d1\u30c3\u30af","monster_watch":"\u30a2\u30cb\u30de\u30b9,\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1,\u771f\u30fb\u661f\u9f8d\u30a6\u30a9\u30c3\u30c1","monster_skill_type":"\u30dc\u30fc\u30ca\u30b9\u7389\u304c\u964d\u3063\u3066\u304f\u308b","class_list":["post-170377","monster","type-monster","status-publish","has-post-thumbnail","hentry","monster_species-1216","monster_rank-z","special_type-1509","monster_feature-1791","monster_watch-1196","monster_watch-1669","monster_watch-1805","monster_skill_type-1350"],"long_title":"\u3010\u3077\u306b\u3077\u306b\u3011\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3\u306e\u5165\u624b\u65b9\u6cd5\u3068\u80fd\u529b\u8a55\u4fa1 [\u3061\u3087\u3046\u304b\u304f\u305b\u3044\u3052\u304d\u3069\u3089\u3054\u3093]\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3011","user":"mihomura","str_count":447,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"noindex":false,"comment_count":0,"original_content":"","site_name":"\u5996\u602a\u30a6\u30a9\u30c3\u30c1\u3077\u306b\u3077\u306b","is_valid_post_type":true,"is_password_required":false,"ogp_image_url":"https:\/\/tfi.gamepedia.jp\/image\/w=1200,h=630,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/03\/17031804\/IMG_9690.jpeg","thumbnail_url":"https:\/\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/15\/2024\/03\/17031804\/IMG_9690.jpeg","kana":"\u3061\u3087\u3046\u304b\u304f\u305b\u3044\u3052\u304d\u3069\u3089\u3054\u3093","name":"\u8d85\u899a\u9192\u6fc0\u30c9\u30e9\u30b4\u30f3","number":"8223","score":"","score_rank":"","rank_order":"9","special_name":"\u30c9\u30e9\u30b4\u30f3\u6fc0\u4e00\u767a","special_description":"\u5168\u3066\u306e\u5996\u602a\u3077\u306b\u3092\u6d88\u3057 1\u4f53\u653b\u6483","special_min_effect":"","special_max_effect":"","special_max_level":"","max_attack":"1034","max_hp":"899","min_attack":"586","min_hp":"509","all":"2450","source":"","_links":{"self":[{"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monsters\/170377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monsters"}],"about":[{"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/types\/monster"}],"author":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/comments?post=170377"}],"version-history":[{"count":3,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monsters\/170377\/revisions"}],"predecessor-version":[{"id":170610,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monsters\/170377\/revisions\/170610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/media\/170360"}],"wp:attachment":[{"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/media?parent=170377"}],"wp:term":[{"taxonomy":"monster_species","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_species?post=170377"},{"taxonomy":"monster_rank","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_rank?post=170377"},{"taxonomy":"special_type","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/special_type?post=170377"},{"taxonomy":"monster_favorite","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_favorite?post=170377"},{"taxonomy":"monster_feature","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_feature?post=170377"},{"taxonomy":"monster_watch","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_watch?post=170377"},{"taxonomy":"monster_skill_type","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/punipuni\/wp-json\/wp\/v2\/monster_skill_type?post=170377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}