{"id":1133,"date":"2016-09-29T16:25:52","date_gmt":"2016-09-29T07:25:52","guid":{"rendered":"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1133"},"modified":"2021-09-21T17:56:27","modified_gmt":"2021-09-21T08:56:27","slug":"%e3%81%9f%e3%81%ae%e3%81%bf%e3%81%94%e3%81%a8-%e5%a6%96%e6%80%aa%e3%81%9f%e3%81%a1%e3%81%ae%e5%ae%b4%e4%bc%9a","status":"publish","type":"quest","link":"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1133","title":{"rendered":"\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c11\u3011\u305f\u306e\u307f\u3054\u3068\u300c\u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a\u300d\u306e\u653b\u7565\u60c5\u5831\u307e\u3068\u3081\u3010\u30b9\u30de\u30db\u30fb\u30b9\u30a4\u30c3\u30c1\u3011"},"content":{"rendered":"\n\n<img decoding=\"async\" class=\"\" style=\"max-width:200px;\" src=\"https:\/\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21175622\/aa8b8adbe2fe3a0cdffc44bf9c311eaf.jpg\" width=\"\" height=\"\" loading=\"lazy\"\/>\n\n<h2  class=\"\"><small>\u305f\u306e\u307f\u3054\u3068<\/small> \u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a<\/h2>\n<div>\n\n<\/div><div>\n\n<\/div><div>\n\n<\/div>\n<h2  class=\"headline\">\u30af\u30a8\u30b9\u30c8\u306e\u767a\u751f\u6761\u4ef6<\/h2>\n<div style=\"line-height:2.0em;\"><span class=\"note-white \" style=\"\"><a class=\"\" href=\"https:\/\/youkai.gamepedia.jp\/yw1\/stories\/246\" >    \u7b2c11\u7ae0<\/a><\/span>\n&nbsp;<span class=\"note-white\">\u30a6\u30a9\u30c3\u30c1\u30e9\u30f3\u30af <span class=\"hutoaka\">A<\/span><\/span> <span class=\"note-white\">\u5e38\u6642<\/span> \n\n<h3  class=\"\">\u767a\u751f\u5834\u6240<\/h3>\n<div class=\"note-white\" style=\"\"><a class=\"\" href=\"https:\/\/youkai.gamepedia.jp\/yw1\/areas\/229\" >    \u56e3\u3005\u5742<\/a> \u7af9\u6797\u306e\u304a\u3093\u307c\u308d\u5c4b\u6577\u3000\u6bcd\u5c4b\u3067\u767a\u751f<\/div>\n\n\n<h3  class=\"\">\u524d\u63d0\u30af\u30a8\u30b9\u30c8<\/h3>\n<span class=\"note-white\" style=\"\"><a class=\"\" href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1131\" >    \u307f\u3093\u306a\u3092\u96c6\u3081\u3066\uff01<\/a><\/span>\n&nbsp;<\/div>\n<h2  class=\"headline\">\u624b\u306b\u5165\u308b\u3082\u306e<\/h2>\n\n<span class=\"label label-att\">\u3051\u3044\u3051\u3093\u3061<\/span><span class=\"label label-value\">1736<\/span>\n<ul class=\"media-list image-grid row \">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/equipments\/1467\">\n    <div class=\"media media-equipment media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2021\/07\/30164015\/8d71d70c68c59ef55965de6ae7a50039.png\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u88c5\u5099\">\u88c5\u5099<\/span>\n                \n              <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u661f\u96f2\u306e\u304a\u307e\u3082\u308a              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div>\n<span class=\"label label-att\">\u3088\u3046\u3058\u3085\u3064<\/span><span class=\"label label-value\">-20<\/span>\n\n<span class=\"label label-att\">\u307e\u3082\u308a<\/span><span class=\"label label-value\">35<\/span>\n<\/div><div class=\"note-white inline-block\">\u305f\u306e\u307f\u3054\u3068\u300c\u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a\u300d\u3067\u5165\u624b\u3001\u5de5\u4e8b\u73fe\u5834\u3067\u5165\u624b<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n            <\/div>\n<\/ul>\n<div class=\"\" style=\"\"><h2 class=\"headline\">\u30af\u30a8\u30b9\u30c8\u306e\u653b\u7565\u30c1\u30e3\u30fc\u30c8<\/h2>\n<ol>\n<li>\u5bb4\u4f1a\u306b\u6765\u3066\u3044\u308b\u5996\u602a\u305f\u3061\u3068\u8a71\u3059<\/li>\n<li>\u3064\u3065\u3089\u30c1\u30e5\u30f3\u592a\u592b\u306b\u8a71\u3057\u304b\u3051\u3001\u30d0\u30c8\u30eb\u3067\u5012\u3059<\/li>\n<\/ol>\n<\/div>\n<hr class=\"\" style=\"\" data-symbol=\"\" \/>\n\n\n<h3  class=\"headline\">\u95a2\u9023\u30b9\u30c8\u30fc\u30ea\u30fc<\/h3>\n<div class=\"media-card\">\n<div class=\"media story\" >\n        <div class=\"media-left\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/stories\/246\">\n        <img decoding=\"async\" class=\"img-thumbnail img-responsive media-object\" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2021\/09\/25160305\/f381ad5884aaa4b37a5be8930979e010-480x255.jpg\" width=\"200\" height=\"200\" loading=\"lazy\"\/>\n        \n      <\/a>\n    <\/div>\n        <div class=\"media-body\">\n      <div class=\"media-body-inner\">\n        <a  href=\"https:\/\/youkai.gamepedia.jp\/yw1\/stories\/246\">\n        <div class=\"media-heading\">\u7b2c11\u7ae0\u300c\u3055\u3088\u306a\u3089\u5996\u602a\u30ef\u30fc\u30eb\u30c9\u300d                <\/div>\n        <\/a>\n        <div class=\"media-meta\">\n                    \n\n                              \n\n        <\/div>\n\n        <div class=\"media-desc\">\n                  <\/div>\n      <\/div>\n\n            <a class=\"media-btn btn btn-default\" href=\"https:\/\/youkai.gamepedia.jp\/yw1\/stories\/246\" ><i class=\"fa fa-external-link\"><\/i> \u7d9a\u304d\u3092\u8aad\u3080<\/a>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n\n<h3  class=\"\">\u7b2c11\u7ae0\u306e\u30af\u30a8\u30b9\u30c8<\/h3>\n<ul class=\"media-list image-grid row embeds archive-list\">\n  <div>\n  \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1132\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21175427\/ae86cbc6000d20712263e18fad10e272-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u3055\u304f\u3089\u30cb\u30e5\u30fc\u30bf\u30a6\u30f3 \u3055\u304f\u3089\u7b2c\u4e00\u5c0f\u5b66\u6821\">\u3055\u304f\u3089\u30cb\u30e5\u30fc\u30bf\u30a6\u30f3 \u3055\u304f\u3089\u7b2c\u4e00\u5c0f\u5b66\u6821<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30a2\u30eb\u30c6\u30a3\u30e1\u30c3\u30c8\u304a\u306b\u3054\u3063\u3053              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u6d41\u661f\u306e\u30d0\u30c3\u30b8<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1133\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21175622\/aa8b8adbe2fe3a0cdffc44bf9c311eaf-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u56e3\u3005\u5742 \u7af9\u6797\u306e\u304a\u3093\u307c\u308d\u5c4b\u6577\u3000\u6bcd\u5c4b\">\u56e3\u3005\u5742 \u7af9\u6797\u306e\u304a\u3093\u307c\u308d\u5c4b\u6577\u3000\u6bcd\u5c4b<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u661f\u96f2\u306e\u304a\u307e\u3082\u308a<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1134\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21175904\/d20a66dd4a698e1ece8b15e84b696f6a-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u304a\u3064\u304b\u3044\u6a2a\u4e01 \u30b3\u30a4\u30f3\u30e9\u30f3\u30c9\u30ea\u30fc\u3000\u30e1\u30ea\u30fc\">\u304a\u3064\u304b\u3044\u6a2a\u4e01 \u30b3\u30a4\u30f3\u30e9\u30f3\u30c9\u30ea\u30fc\u3000\u30e1\u30ea\u30fc<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u30dc\u30b9\u732b\u3092\u3055\u304c\u305b              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u30bf\u30d5\u30d9\u30eb<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1135\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21180246\/5bd2e0be97810365b79f15f8e7978f49-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u56e3\u3005\u5742 \u7af9\u3084\u3076\u306e\u9053\">\u56e3\u3005\u5742 \u7af9\u3084\u3076\u306e\u9053<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u5e7b\u306e\u9aa8\u8463\u54c1\u3092\u63a2\u305b\uff01              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u30bb\u30df\u5fcd\u5200\u3001\u540d\u5200\u30de\u30b5\u30e0\u30cd\u3001\u5996\u5200\u30e0\u30e9\u30de\u30b5<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1136\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21180350\/186b01ad3e5f0064b44db4691c7f49cf-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u305d\u3088\u98a8\u30d2\u30eb\u30ba \u3072\u3087\u3046\u305f\u3093\u6c60\u535a\u7269\u9928\u30002\u968e\">\u305d\u3088\u98a8\u30d2\u30eb\u30ba \u3072\u3087\u3046\u305f\u3093\u6c60\u535a\u7269\u9928\u30002\u968e<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u304a\u3058\u3055\u3093\u306e\u9577\u8a71              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u6e05\u8056\u6c34<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n          \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1137\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21180445\/fb157a301ef479201faee5b43db34617-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u3055\u304f\u3089\u30cb\u30e5\u30fc\u30bf\u30a6\u30f3 \u3055\u3093\u304b\u304f\u516c\u5712\">\u3055\u304f\u3089\u30cb\u30e5\u30fc\u30bf\u30a6\u30f3 \u3055\u3093\u304b\u304f\u516c\u5712<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u51fa\u3089\u308c\u306a\u3044\u6559\u5ba4              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u304a\u3055\u308b\u306e\u8f2a\u3063\u304b<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n        <div class=\"clearfix visible-xs\" ><\/div>\n            <div class=\"clearfix hidden-xs\" ><\/div>\n      \n\n    <div class=\"col-xs-4 col-sm-2\">\n      <a href=\"https:\/\/youkai.gamepedia.jp\/yw1\/quests\/1138\">\n    <div class=\"media media-quest media-square \" style=\"\" >\n    \n    <div class=\"media-object\">\n            <img decoding=\"async\" class=\"img-responsive \" style=\"\" src=\"https:\/\/tfi.gamepedia.jp\/image\/w=400,h=400,fit=pad,f=webp\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21180542\/8ed644a9856c1be12edeed09fa99fa50-480x255.jpg\" loading=\"lazy\" width=\"400\" height=\"400\"\/>\n      <div class=\"media-terms\">\n\n                        <span class=\"label label-default label-post-type label-post-type-\u305f\u306e\u307f\u3054\u3068\">\u305f\u306e\u307f\u3054\u3068<\/span>\n                \n                                        <span class=\"label label-default label-quest_story label-quest_story-\u7b2c11\u7ae0\">\u7b2c11\u7ae0<\/span>\n                                                <span class=\"label label-default label-map label-map-\u56e3\u3005\u5742 \u9ce5\u98fc\u5bb6\u3000\u5927\u5e83\u9593\">\u56e3\u3005\u5742 \u9ce5\u98fc\u5bb6\u3000\u5927\u5e83\u9593<\/span>\n                                      <\/div>\n    <\/div>\n    <div class=\"media-body\">\n      <div class=\"media-heading\">\n\n        \u602a\u9ce5\u30b3\u30ec\u30af\u30b7\u30e7\u30f3\u2461              <\/div>\n\n\n      <div class=\"media-desc\">\n        <div class=\"note-white\">\u5831\u916c\uff1a\u30aa\u30ed\u30c1\u306e\u30aa\u30fc\u30e9<\/div>      <\/div>\n\n\n\n    <\/div>\n  <\/div>\n  <\/a>\n      <\/div>\n\n            <\/div>\n<\/ul>\n","protected":false},"author":1,"featured_media":5933,"menu_order":95,"comment_status":"open","ping_status":"closed","template":"","meta":{"event_start_date":[],"event_end_date":[],"external_thumbnail_url":"","redirect":"","last_comment_date":"2025-10-09 05:44:12","footnotes":"","name":"\u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a","kana":"","story":"\u7b2c11\u7ae0","map":"\u56e3\u3005\u5742","condition_quests":"\u307f\u3093\u306a\u3092\u96c6\u3081\u3066\uff01","requires":"","drops":"\u661f\u96f2\u306e\u304a\u307e\u3082\u308a"},"quest_story":"\u7b2c11\u7ae0","class_list":["post-1133","quest","type-quest","status-publish","has-post-thumbnail","hentry","quest_story-25"],"long_title":"\u3010\u5996\u602a\u30a6\u30a9\u30c3\u30c11\u3011\u305f\u306e\u307f\u3054\u3068\u300c\u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a\u300d\u306e\u653b\u7565\u60c5\u5831\u307e\u3068\u3081\u3010\u30b9\u30de\u30db\u30fb\u30b9\u30a4\u30c3\u30c1\u3011","user":"hiro","str_count":57,"category_name":"","tag_name":"","is_pr":false,"pr_mode":null,"hide_ad":false,"comment_count":6,"original_content":"","site_name":"\u5996\u602a\u30a6\u30a9\u30c3\u30c11","is_valid_post_type":true,"is_password_required":false,"thumbnail_url":"https:\/\/media.gamepedia.jp\/youkai.gamepedia.com\/wp-content\/uploads\/sites\/9\/2016\/09\/21175622\/aa8b8adbe2fe3a0cdffc44bf9c311eaf.jpg","name":"\u5996\u602a\u305f\u3061\u306e\u5bb4\u4f1a","kana":"","story":"\u7b2c11\u7ae0","map":"\u56e3\u3005\u5742","condition_quests":"\u307f\u3093\u306a\u3092\u96c6\u3081\u3066\uff01","requires":"","drops":"\u661f\u96f2\u306e\u304a\u307e\u3082\u308a","_links":{"self":[{"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/quests\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/quests"}],"about":[{"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/types\/quest"}],"author":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":2,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/quests\/1133\/revisions"}],"predecessor-version":[{"id":5934,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/quests\/1133\/revisions\/5934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/media\/5933"}],"wp:attachment":[{"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"quest_story","embeddable":true,"href":"https:\/\/youkai.gamepedia.jp\/yw1\/wp-json\/wp\/v2\/quest_story?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}